{"id":773,"count":1,"description":"","link":"https:\/\/www.horsemagazine.com\/thm\/tag\/the-springpferdezuchtverband-oldenburg-international-os\/","name":"The Springpferdezuchtverband Oldenburg-International (OS)","slug":"the-springpferdezuchtverband-oldenburg-international-os","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.horsemagazine.com\/thm\/wp-json\/wp\/v2\/tags\/773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.horsemagazine.com\/thm\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.horsemagazine.com\/thm\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.horsemagazine.com\/thm\/wp-json\/wp\/v2\/posts?tags=773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}